{"id":2433,"date":"2024-01-25T13:37:20","date_gmt":"2024-01-25T12:37:20","guid":{"rendered":"https:\/\/egoitalianostore.com\/napolivomero\/prodotto\/pinocchio\/"},"modified":"2024-01-25T13:37:20","modified_gmt":"2024-01-25T12:37:20","slug":"pinocchio","status":"publish","type":"product","link":"https:\/\/egoitalianostore.com\/napolivomero\/prodotti\/complementi\/lampade\/pinocchio\/","title":{"rendered":"Pinocchio"},"content":{"rendered":"<p>PINOCCHIO \u00e8 un tavolino che si crede una lampada e una lampada che si crede un tavolino. PINOCCHIO infatti \u00e8 una lampada in legno massello di frassino con tavolino in metallo integrato. Disponibile nelle tinte rovere naturale con cavo bordeux o noce canaletto con cavo azzurro, Pinocchio ha anche il suo pap\u00e0, la lampada\u00a0<a href=\"https:\/\/www.egoitaliano.com\/prodotti\/lampada-geppetto\/\" rel=\"nofollow noopener\" target=\"_blank\">GEPPETTO<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PINOCCHIO \u00e8 un tavolino che si crede una lampada e una lampada che si crede un tavolino. PINOCCHIO infatti \u00e8 una lampada in legno massello di frassino con tavolino in metallo integrato. Disponibile nelle tinte rovere naturale con cavo bordeux o noce canaletto con cavo azzurro, Pinocchio ha anche il suo pap\u00e0, la lampada\u00a0<a href=\"https:\/\/www.egoitaliano.com\/prodotti\/lampada-geppetto\/\">GEPPETTO<\/a>.<\/p>\n","protected":false},"featured_media":1862,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_crosspost_to_1":false,"_crosspost_to_4":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_12":false,"_crosspost_to_13":false,"_crosspost_to_14":false,"_crosspost_to_16":false,"_crosspost_to_17":false,"_crosspost_to_18":false,"_crosspost_to_19":false,"_crosspost_to_22":false,"_crosspost_to_23":false,"_crosspost_to_25":false,"_crosspost_to_26":false,"_crosspost_to_28":false,"_crosspost_to_29":false,"_crosspost_to_32":false,"_crosspost_to_33":false,"_crosspost_to_38":false,"_crosspost_to_39":false,"_crosspost_to_40":false,"_crosspost_to_41":false,"_crosspost_to_42":false,"_crosspost_to_43":false},"product_brand":[],"product_cat":[32,34,37],"product_tag":[],"class_list":{"0":"post-2433","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-complementi","7":"product_cat-lampade","8":"product_cat-tavolini","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product\/2433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/comments?post=2433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/media\/1862"}],"wp:attachment":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/media?parent=2433"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_brand?post=2433"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_cat?post=2433"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_tag?post=2433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}