{"id":2498,"date":"2024-01-25T14:55:37","date_gmt":"2024-01-25T13:55:37","guid":{"rendered":"https:\/\/egoitalianostore.com\/napolivomero\/prodotto\/multiverso\/"},"modified":"2024-01-25T14:55:37","modified_gmt":"2024-01-25T13:55:37","slug":"multiverso","status":"publish","type":"product","link":"https:\/\/egoitalianostore.com\/napolivomero\/prodotti\/complementi\/wallpaper\/multiverso\/","title":{"rendered":"Multiverso"},"content":{"rendered":"<p>Forme astratte, linee e motivi geometrici dal sapore retr\u00f2 si incontrano per un effetto optical nella serie MULTIVERSO, le carte da parati che decorano con dinamismo ogni ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forme astratte, linee e motivi geometrici dal sapore retr\u00f2 si incontrano per un effetto optical nella serie MULTIVERSO, le carte da parati che decorano con dinamismo ogni ambiente.<\/p>\n","protected":false},"featured_media":1356,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_crosspost_to_1":false,"_crosspost_to_4":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_12":false,"_crosspost_to_13":false,"_crosspost_to_14":false,"_crosspost_to_16":false,"_crosspost_to_17":false,"_crosspost_to_18":false,"_crosspost_to_19":false,"_crosspost_to_22":false,"_crosspost_to_23":false,"_crosspost_to_25":false,"_crosspost_to_26":false,"_crosspost_to_28":false,"_crosspost_to_29":false,"_crosspost_to_32":false,"_crosspost_to_33":false,"_crosspost_to_38":false,"_crosspost_to_39":false,"_crosspost_to_40":false,"_crosspost_to_41":false,"_crosspost_to_42":false,"_crosspost_to_43":false},"product_brand":[],"product_cat":[32,38],"product_tag":[],"class_list":{"0":"post-2498","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-complementi","7":"product_cat-wallpaper","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product\/2498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/comments?post=2498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/media\/1356"}],"wp:attachment":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/media?parent=2498"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_brand?post=2498"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_cat?post=2498"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_tag?post=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}