{"id":2896,"date":"2025-01-29T22:22:14","date_gmt":"2025-01-29T21:22:14","guid":{"rendered":"https:\/\/egoitalianostore.com\/napolivomero\/prodotti\/senza-categoria\/fiorello\/"},"modified":"2025-01-29T22:22:14","modified_gmt":"2025-01-29T21:22:14","slug":"fiorello","status":"publish","type":"product","link":"https:\/\/egoitalianostore.com\/napolivomero\/prodotti\/complementi\/cuscini\/fiorello\/","title":{"rendered":"Fiorello"},"content":{"rendered":"<p><strong>FIORELLO<\/strong> \u00e8 il simpatico guanciale a forma di fiore disponibile in tantissimi colori.Scoprili dal rivenditore Egoitaliano pi\u00f9 vicino a te, porteranno ironia e leggerezza in ogni ambiente.<br \/>\nDiametro 40 cm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>FIORELLO<\/strong> \u00e8 il simpatico guanciale a forma di fiore disponibile in tantissimi colori.Scoprili dal rivenditore Egoitaliano pi\u00f9 vicino a te, porteranno ironia e leggerezza in ogni ambiente.<br \/>\nDiametro 40 cm.<\/p>\n","protected":false},"featured_media":2901,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_crosspost_to_1":false,"_crosspost_to_4":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_12":false,"_crosspost_to_13":false,"_crosspost_to_14":false,"_crosspost_to_16":false,"_crosspost_to_17":false,"_crosspost_to_18":false,"_crosspost_to_19":false,"_crosspost_to_22":false,"_crosspost_to_23":false,"_crosspost_to_25":false,"_crosspost_to_26":false,"_crosspost_to_28":false,"_crosspost_to_29":false,"_crosspost_to_32":false,"_crosspost_to_33":false,"_crosspost_to_38":false,"_crosspost_to_39":false,"_crosspost_to_40":false,"_crosspost_to_41":false,"_crosspost_to_42":false,"_crosspost_to_43":false},"product_brand":[],"product_cat":[32,33,42],"product_tag":[],"class_list":{"0":"post-2896","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-complementi","7":"product_cat-cuscini","8":"product_cat-novita","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product\/2896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/comments?post=2896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/media\/2901"}],"wp:attachment":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/media?parent=2896"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_brand?post=2896"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_cat?post=2896"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_tag?post=2896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}