{"id":34,"count":13,"description":"Illumina il tuo spazio con le nostre lampade dal design innovativo. Un tocco di stile per creare un'atmosfera accogliente in ogni angolo.","link":"https:\/\/egoitalianostore.com\/napolivomero\/categoria-prodotto\/complementi\/lampade\/","name":"Lampade","slug":"lampade","taxonomy":"product_cat","parent":32,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_cat\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product_cat\/32"}],"wp:post_type":[{"href":"https:\/\/egoitalianostore.com\/napolivomero\/wp-json\/wp\/v2\/product?product_cat=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}